{"id":349,"date":"2024-04-11T17:08:30","date_gmt":"2024-04-11T09:08:30","guid":{"rendered":"https:\/\/jlcoating.com\/?p=349"},"modified":"2024-05-15T11:16:47","modified_gmt":"2024-05-15T03:16:47","slug":"aha2148","status":"publish","type":"post","link":"https:\/\/www.jlcoating.com\/es_es\/aha2148\/","title":{"rendered":"AHA2148"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Descripci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2148 <\/strong>es un endurecedor mate sin cera adecuado para recubrimientos en polvo TGIC duraderos para exteriores capaces de proporcionar un brillo &lt;10% a 60\u00b0. Debido a que contiene grupos carboxilo, se requiere un exceso de TGIC reactivo junto con \u00e9l para lograr un brillo controlable y una excelente estabilidad del brillo en condiciones de horneado a diferentes temperaturas. Los beneficios adicionales son un rendimiento excelente, como impactos y flujo superficial aceptable, etc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Propiedades tipicas<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Apariencia<\/td><td>polvo amarillo p\u00e1lido que fluye libremente<\/td><\/tr><tr><td>Rango de fusi\u00f3n (\u2103)<\/td><td>110-135<\/td><\/tr><tr><td>Peso equivalente \u00e1cido<\/td><td>750<\/td><\/tr><tr><td>Densidad aparente (g\/dm3)<\/td><td>450-550<\/td><\/tr><tr><td>Vol\u00e1tiles (%)<\/td><td>\u22641,5<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Solicitud<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2148 <\/strong>Se recomienda como endurecedor mate utilizado en recubrimientos en polvo de poli\u00e9ster\/TGIC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ventajas:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mate de un solo disparo<\/li>\n\n\n\n<li>Brillo estable en diferentes condiciones de temperatura.<\/li>\n\n\n\n<li>Sin cera evitando el efecto negativo de la cera.<\/li>\n\n\n\n<li>Baja selectividad de poli\u00e9ster<\/li>\n\n\n\n<li>El brillo m\u00e1s bajo ca. 10%<\/li>\n\n\n\n<li>Flujo aceptable y finura superficial<\/li>\n\n\n\n<li>Excelentes impactos<\/li>\n\n\n\n<li>Buena durabilidad exterior gracias al AHA2148-self con rayos anti-UV<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Nivel de uso<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">3- 6% basado en la formulaci\u00f3n total en peso, dependiendo del brillo requerido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2148 <\/strong>Contiene grupos funcionales reactivos, por lo que se requiere que participe en la reacci\u00f3n con exceso de TGIC en la formulaci\u00f3n. En general, se recomendaron proporciones de mezcla de 6,5 a 7,5\/1 en peso de AHA2148 con respecto al exceso de TGIC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Horarios de curado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">15 min a 180 \u2103 o 10 min a 200 \u2103<\/p>","protected":false},"excerpt":{"rendered":"<p>Description AHA2148 is a wax-free matting hardener suitable for exterior durable TGIC powder coatings capable of providing gloss\uff1c10% @ 60\u00b0. Due to carboxyl group-containing it is requested excess TGIC reactive with it together to achieve controllable gloss and excellent gloss stability in varying temperature baking conditions. Additional benefits are excellent performance such as impacts and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,12],"tags":[19],"class_list":["post-349","post","type-post","status-publish","format-standard","hentry","category-matting-solutions","category-outdoor","tag-matting-solutions"],"_links":{"self":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/comments?post=349"}],"version-history":[{"count":3,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/349\/revisions"}],"predecessor-version":[{"id":746,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/349\/revisions\/746"}],"wp:attachment":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/media?parent=349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/categories?post=349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/tags?post=349"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}