{"id":345,"date":"2024-04-11T16:37:41","date_gmt":"2024-04-11T08:37:41","guid":{"rendered":"https:\/\/jlcoating.com\/?p=345"},"modified":"2024-05-15T11:19:25","modified_gmt":"2024-05-15T03:19:25","slug":"aha2137","status":"publish","type":"post","link":"https:\/\/www.jlcoating.com\/es_es\/aha2137\/","title":{"rendered":"AHA2137"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Descripci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2137 <\/strong>es un tipo de agente mateante sin cera adecuado para recubrimientos en polvo duraderos para exteriores a base de \u03b2-hidroxialquilamida (HAA) mate de una sola aplicaci\u00f3n con un brillo que oscila entre 5% y 30% (60\u00b0).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Propiedades tipicas<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Apariencia<\/td><td>Polvo blanco que fluye libremente<\/td><\/tr><tr><td>Rango de fusi\u00f3n (\u00b0C)<\/td><td>120-135<\/td><\/tr><tr><td>Densidad aparente (g\/L)<\/td><td>700-800<\/td><\/tr><tr><td>Vol\u00e1tiles (%)<\/td><td>\u22641,5<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Solicitud<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2137 <\/strong>Se recomienda como agente mateante utilizado en recubrimientos en polvo HAA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ventajas:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mate de un solo disparo<\/li>\n\n\n\n<li>Sin cera evitando el efecto negativo de la cera.<\/li>\n\n\n\n<li>El brillo m\u00e1s bajo ca. 10%<\/li>\n\n\n\n<li>Baja selectividad de poli\u00e9ster<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Nivel de uso<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">5-10% por peso<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Horarios de curado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">200\u00b0C\/15min (temperatura del metal)<\/p>","protected":false},"excerpt":{"rendered":"<p>Description AHA2137 is one kind of wax-free matting agent suitable for one-shot matte \u03b2-hydroxylalkyl amide (HAA) based exterior durable powder coatings with gloss ranges from 5% to 30% (60\u00b0). Typical properties Appearance Free-flowing, white powder Melting range (\u00b0C) 120-135 Bulk density (g\/L) 700-800 Volatiles (%) \u22641.5 Application AHA2137 is recommended as matting agent used in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,12],"tags":[19],"class_list":["post-345","post","type-post","status-publish","format-standard","hentry","category-matting-solutions","category-outdoor","tag-matting-solutions"],"_links":{"self":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/comments?post=345"}],"version-history":[{"count":3,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/345\/revisions"}],"predecessor-version":[{"id":750,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/345\/revisions\/750"}],"wp:attachment":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/media?parent=345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/categories?post=345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/tags?post=345"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}