{"id":339,"date":"2024-04-11T16:21:07","date_gmt":"2024-04-11T08:21:07","guid":{"rendered":"https:\/\/jlcoating.com\/?p=339"},"modified":"2024-05-15T11:21:00","modified_gmt":"2024-05-15T03:21:00","slug":"aha2115","status":"publish","type":"post","link":"https:\/\/www.jlcoating.com\/es_es\/aha2115\/","title":{"rendered":"AHA2115"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Descripci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2115 <\/strong>es un agente mateante a base de resina sint\u00e9tica, no reactivo y sin cera dise\u00f1ado para recubrimientos en polvo h\u00edbridos capaz de proporcionar el brillo m\u00e1s bajo 5%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Propiedades tipicas<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Apariencia<\/td><td>Polvo amarillento p\u00e1lido<\/td><\/tr><tr><td>Rango de fusi\u00f3n (\u00b0C)<\/td><td>110-130<\/td><\/tr><tr><td>Vol\u00e1tiles (%)<\/td><td>\u22641,5<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Solicitud<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se recomienda AHA2115 como agente matificante utilizado en polvos h\u00edbridos para proporcionar el brillo m\u00e1s bajo &lt;5%. Presenta condiciones de curado adecuadas para cualquier poli\u00e9ster t\u00edpico, como 50\/50, 60\/40 y 70\/30, pero se recomienda especialmente el poli\u00e9ster t\u00edpico 50\/50. Y tambi\u00e9n se logra una excelente fluidez\/finura superficial, estabilidad mec\u00e1nica y excelente brillo despu\u00e9s de la operaci\u00f3n de reextrusi\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Niveles de uso<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">1- 5% por peso<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Calendario de curado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">180 \u2103\/20 min. o 190\/15min (temperatura del metal).<\/p>","protected":false},"excerpt":{"rendered":"<p>Description AHA2115 is wax-free, non-reactive and synthetic resin based matting agent designed for hybrid powder coating capable of providing the lowest 5% of gloss. Typical properties Appearance Pale yellowish powder Melting range (\u00b0C) 110-130 Volatiles (%) \u22641.5 Application AHA2115 is recommended as matting agent used in hybrid powders to provide the lowest\uff1c5% of gloss. It [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,5],"tags":[19],"class_list":["post-339","post","type-post","status-publish","format-standard","hentry","category-indoor","category-matting-solutions","tag-matting-solutions"],"_links":{"self":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":4,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"predecessor-version":[{"id":755,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/339\/revisions\/755"}],"wp:attachment":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/categories?post=339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/tags?post=339"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}