{"id":333,"date":"2024-04-11T16:07:09","date_gmt":"2024-04-11T08:07:09","guid":{"rendered":"https:\/\/jlcoating.com\/?p=333"},"modified":"2024-05-15T11:22:42","modified_gmt":"2024-05-15T03:22:42","slug":"aha2029","status":"publish","type":"post","link":"https:\/\/www.jlcoating.com\/es_es\/aha2029\/","title":{"rendered":"AHA2029"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Descripci\u00f3n<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2029 <\/strong>es una versi\u00f3n profundamente modificada y con bajo contenido de cera del anterior AHA2019. Este producto proporciona menor brillo, mejor flujo y rendimiento t\u00e9cnico general. Adem\u00e1s, se caracteriza por una excelente estabilidad del color y una mejor reducci\u00f3n de vol\u00e1tiles y olores en el procesamiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Datos f\u00edsicos t\u00edpicos<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Apariencia<\/td><td>polvo blanco<\/td><\/tr><tr><td>Rangos de fusi\u00f3n (\u00b0C)<\/td><td>150-165<\/td><\/tr><tr><td>Densidad aparente (g\/l)<\/td><td>680<\/td><\/tr><tr><td>Vol\u00e1tiles (%)<\/td><td>\u22642<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Solicitud<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AHA2029 <\/strong>Se recomienda como agente mateante, junto con las resinas de poli\u00e9ster COOH, utilizadas en recubrimientos en polvo duraderos para exteriores a base de TGIC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ventajas:<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bajo contenido de cera<\/li>\n\n\n\n<li>El brillo m\u00e1s bajo se acerca <strong>a 5% (negro<\/strong>)<\/li>\n\n\n\n<li>Excelente flujo<\/li>\n\n\n\n<li>Excelente antiamarilleo<\/li>\n\n\n\n<li>Un disparo, f\u00e1cil de usar y rociar<\/li>\n\n\n\n<li>Mejor resistencia al bru\u00f1ido<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Niveles de uso<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">3- 5.5% <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Horarios de curado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">200\u00b0C\/8-10min<\/p>","protected":false},"excerpt":{"rendered":"<p>Description AHA2029 is a deep modified, low wax-containing version of former AHA2019. This product provides lower gloss, better flow and overall technical performances. In addition, it is featured by excellent color stability and improved volatile and smell-reducing in processing. Typical physical data Appearance White powder Melting ranges(\u00b0C) 150-165 Bulk density (g\/l) 680 Volatiles (%) \u22642 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,12],"tags":[19],"class_list":["post-333","post","type-post","status-publish","format-standard","hentry","category-matting-solutions","category-outdoor","tag-matting-solutions"],"_links":{"self":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/comments?post=333"}],"version-history":[{"count":3,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/333\/revisions"}],"predecessor-version":[{"id":757,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/333\/revisions\/757"}],"wp:attachment":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/media?parent=333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/categories?post=333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/tags?post=333"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}