{"id":255,"date":"2024-04-10T13:29:58","date_gmt":"2024-04-10T05:29:58","guid":{"rendered":"https:\/\/jlcoating.com\/?p=255"},"modified":"2024-05-21T13:25:42","modified_gmt":"2024-05-21T05:25:42","slug":"aha6552","status":"publish","type":"post","link":"https:\/\/www.jlcoating.com\/es_es\/aha6552\/","title":{"rendered":"AHA6552"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Descripci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">AHA6552 es un grupo tetrafuncional que contiene un reticulante de \u03b2-hidroxialquilamida. Como sustituto del TGIC, es adecuado para curar con poli\u00e9ster terminado en carboxilo o resina acr\u00edlica para proporcionar recubrimientos en polvo duraderos para exteriores con base libre de TGIC.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Propiedades tipicas<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Apariencia<\/td><td>Visual<\/td><td>pastillas blancas<\/td><\/tr><tr><td>Intervalo de fusi\u00f3n<\/td><td>\u00b0C<\/td><td>120-130<\/td><\/tr><tr><td>n\u00famero de hidroxi<\/td><td>mgKOH\/g<\/td><td>620-700<\/td><\/tr><tr><td>Vol\u00e1tiles (%)<\/td><td>%<\/td><td>\u22641<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Niveles de proceso y uso<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se a\u00f1ade AHA6552 a la mezcla de aglutinante\/pigmento antes de la extrusi\u00f3n.<br>Se recomienda dise\u00f1ar una formulaci\u00f3n en partes en peso de 95\/5 (resina seg\u00fan AHA6552) para resina de poli\u00e9ster pura con AV ca 34 mgKOH\/g; 96,5\/3,5 en peso para resina de poli\u00e9ster con AV ca. 22 mg de KOH\/g.<\/p>","protected":false},"excerpt":{"rendered":"<p>Description AHA6552 is a tetra-functional group containing \u03b2-hydroxyalkylamide crosslinker. As a substitute of TGIC, it is suitable for curing with carboxyl-terminated polyester or acrylic resin to provide TGIC-free based exterior durable powder coatings. Typical properties Appearance Visual White pills Melting range \u00b0C 120-130 Hydroxy number mgKOH\/g 620-700 Volatiles (%) % \u22641 Process &amp; Use levels [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[18],"class_list":["post-255","post","type-post","status-publish","format-standard","hentry","category-crosslinkers-and-hardeners","tag-crosslinkers-and-hardeners"],"_links":{"self":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/comments?post=255"}],"version-history":[{"count":15,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/255\/revisions"}],"predecessor-version":[{"id":874,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/posts\/255\/revisions\/874"}],"wp:attachment":[{"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/media?parent=255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/categories?post=255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jlcoating.com\/es_es\/wp-json\/wp\/v2\/tags?post=255"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}